{"id":45126,"date":"2018-04-18T18:33:33","date_gmt":"2018-04-18T15:33:33","guid":{"rendered":"https:\/\/btv.md\/?p=45126"},"modified":"2018-04-18T18:33:33","modified_gmt":"2018-04-18T15:33:33","slug":"festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul","status":"publish","type":"post","link":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/","title":{"rendered":"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul"},"content":{"rendered":"<p style=\"text-align: center;\"><iframe data-src=\"https:\/\/www.youtube.com\/embed\/fsGD8Yiqtng\" width=\"854\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p><strong>Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery. Oganizatorul proiectului \u00een Moldova,Valeriu Culea este fondatorul \u201eJazz\u2019n Chi\u015fin\u0103u\u201d unde are loc cea de-a VI-a edi\u0163ie a festivalului. \u00cen acest an evenimentul a adunat participan\u021bi din SUA, Elve\u021bia, Italia, Polonia, Ukraina \u015fi Moldova.<\/strong><\/p>\n<p>Margareta Tetelea, \u015fefa sec\u0163iei de cultur\u0103 \u015fi via\u0163\u0103 studen\u0163iasc\u0103 USARB: <em>\u201eEste \u00eentr-adev\u0103r un eveniment foarte frumos pentru universitatea noastr\u0103, \u00een special pentru Filarmonica noastr\u0103 pentru copii care activeaz\u0103 undeva 20\u00a0 de ni pe l\u00e2ng\u0103 universitate, centru cultural artistic care valorific\u0103 tot ce este frumos din domeniul muzicii mari. Sigur c\u0103 jazz-ul este muzic\u0103 clasic\u0103, un gen de muzic\u0103 clasic\u0103 care presupune educa\u0163ia unor st\u0103ri, unor sentimente ale personalit\u0103\u0163ii \u015fi ne bucur\u0103m nespus de mult c\u0103 aceast\u0103 muzic\u0103 rar\u0103 mai vine \u015fi\u00a0 pe la B\u0103l\u0163i.\u201d<\/em><\/p>\n<p>P\u00e2n\u0103 pe 19 aprilie, \u00een cadrul festivalului, vor fi organizate concerte la Chi\u0219in\u0103u, B\u0103l\u021bi, Tiraspol \u0219i Cahul.<\/p>\n<p>Liuba Cecevi\u0163ina, reprezentant din Chi\u015fin\u0103u: \u201e<em>A\u015f dori ca cultura s\u0103 se r\u0103sp\u00e2ndeasc\u0103 uniform pe tot teritoriul Republicii Moldova \u015fi to\u0163i s\u0103 simt\u0103 frumusea\u0163ea muzicii, mai ales trupelor din afara \u0163\u0103rii. Domnul Valeriu Culea a adunat pe to\u0163i participan\u0163ii pe care a putut, el singur este jazz-man \u015fi pentru el este interesant.\u201d<\/em><\/p>\n<p>Aga Derlak este o pianist\u0103 din Polonia, o instrumentist\u0103 de genera\u021bie nou\u0103 de nivel European care a ini\u0163iat propria trup\u0103. Din band mai fac parte Tzmon Trabczynski. care c\u00e2nt\u0103 la contrabas \u015fi Lukasz Zyta &#8211; la tobe.<\/p>\n<p>Aga Derlak, conduc\u0103toarea trupei \u201eAga Derlak Trio\u201d: <em>\u201eDe fiecare dat\u0103 c\u00e2nd vezit\u0103m \u0163\u0103ri noi \u015fi avem concerte \u00een ele este o aventur\u0103. Noi savur\u0103m locul \u015fi oamenii unde ne afl\u0103m, ne str\u0103duim s\u0103 transmit starea noastr\u0103 de bine, muzica \u015fi emo\u0163iile publicului. Sunt foarte recun\u0103sc\u0103toare \u015fi fericit\u0103 s\u0103 m\u0103 aflu \u00een Moldova, \u00eemi plac oamenii care sunt foarte deschi\u015fi. Sper c\u0103 voi avea posibilitatea s\u0103 revin aici, macar o dat\u0103.\u201d<\/em><\/p>\n<p>Tinerii b\u0103l\u0163eni au un interes sporit pentru muzica modern\u0103.<\/p>\n<p>\u201e\u00cemi place foarte mult muzica contemporan\u0103, jazz, rock, pe care nu le studiem. A\u015f dori s\u0103 m\u0103 aprofund \u00een aceast\u0103 atmosfer\u0103. Din acest motiv am venit s\u0103 m\u0103 uit c\u0103ci pentru mine este o pl\u0103cere.\u201d<\/p>\n<p>Proiectul este sus\u021binut la B\u0103l\u0163i de c\u0103tre: Institutul Polonez \u201eAdam Mickiewicz\u201d, Agen\u021bia Elve\u021bian\u0103 pentru Dezvoltare si Cooperare, Prim\u0103ria B\u0103l\u0163i \u015fi Universitatea de Stat \u201cAlecu Russo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery. Oganizatorul proiectului \u00een Moldova,Valeriu Culea este fondatorul \u201eJazz\u2019n Chi\u015fin\u0103u\u201d unde are loc cea de-a VI-a edi\u0163ie a festivalului. \u00cen acest an evenimentul a adunat participan\u021bi din SUA, Elve\u021bia, Italia, Polonia, Ukraina \u015fi Moldova. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":45127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6353],"tags":[],"class_list":["post-45126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul<\/title>\n<meta name=\"description\" content=\"Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul\" \/>\n<meta property=\"og:description\" content=\"Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/\" \/>\n<meta property=\"og:site_name\" content=\"BTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/btvmoldova\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-18T15:33:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.btv.md\/wp-content\/uploads\/2018\/04\/001-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.btv.md\\\/#\\\/schema\\\/person\\\/b459536a60194184218c40dec648134d\"},\"headline\":\"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul\",\"datePublished\":\"2018-04-18T15:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/\"},\"wordCount\":457,\"image\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.btv.md\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/001-19.jpg\",\"articleSection\":[\"Ora\u0219\"],\"inLanguage\":\"ro-RO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/\",\"url\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/\",\"name\":\"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.btv.md\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/001-19.jpg\",\"datePublished\":\"2018-04-18T15:33:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.btv.md\\\/#\\\/schema\\\/person\\\/b459536a60194184218c40dec648134d\"},\"description\":\"Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery.\",\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.btv.md\\\/ro\\\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.btv.md\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/001-19.jpg\",\"contentUrl\":\"https:\\\/\\\/www.btv.md\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/001-19.jpg\",\"width\":700,\"height\":500},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.btv.md\\\/#website\",\"url\":\"https:\\\/\\\/www.btv.md\\\/\",\"name\":\"BTV\",\"description\":\"\u0411\u0435\u043b\u044c\u0446\u043a\u043e\u0435 \u0442\u0435\u043b\u0435\u0432\u0438\u0434\u0435\u043d\u0438\u0435\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.btv.md\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.btv.md\\\/#\\\/schema\\\/person\\\/b459536a60194184218c40dec648134d\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul","description":"Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/","og_locale":"ro_RO","og_type":"article","og_title":"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul","og_description":"Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery.","og_url":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/","og_site_name":"BTV","article_publisher":"https:\/\/www.facebook.com\/btvmoldova\/","article_published_time":"2018-04-18T15:33:33+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/www.btv.md\/wp-content\/uploads\/2018\/04\/001-19.jpg","type":"image\/jpeg"}],"author":"admin","twitter_misc":{"Scris de":"admin","Timp estimat pentru citire":"2 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/#article","isPartOf":{"@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/"},"author":{"name":"admin","@id":"https:\/\/www.btv.md\/#\/schema\/person\/b459536a60194184218c40dec648134d"},"headline":"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul","datePublished":"2018-04-18T15:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/"},"wordCount":457,"image":{"@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.btv.md\/wp-content\/uploads\/2018\/04\/001-19.jpg","articleSection":["Ora\u0219"],"inLanguage":"ro-RO"},{"@type":"WebPage","@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/","url":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/","name":"Festival de jazz la B\u0103l\u0163i. Trupa polonez\u0103 \u201cAga Derlak Trio\u201d a impresionat publicul","isPartOf":{"@id":"https:\/\/www.btv.md\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/#primaryimage"},"image":{"@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.btv.md\/wp-content\/uploads\/2018\/04\/001-19.jpg","datePublished":"2018-04-18T15:33:33+00:00","author":{"@id":"https:\/\/www.btv.md\/#\/schema\/person\/b459536a60194184218c40dec648134d"},"description":"Festivalul interna\u0163ional de Jazz a ajuns \u015fi la B\u0103l\u0163i. Trupa polonez\u0103 \u201eAga Derlak Trio\u201d a interpretat melodii din ultimul s\u0103u album \u201eRecovery.","inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.btv.md\/ro\/festival-de-jazz-la-balti-trupa-poloneza-aga-derlak-trio-a-impresionat-publicul\/#primaryimage","url":"https:\/\/www.btv.md\/wp-content\/uploads\/2018\/04\/001-19.jpg","contentUrl":"https:\/\/www.btv.md\/wp-content\/uploads\/2018\/04\/001-19.jpg","width":700,"height":500},{"@type":"WebSite","@id":"https:\/\/www.btv.md\/#website","url":"https:\/\/www.btv.md\/","name":"BTV","description":"\u0411\u0435\u043b\u044c\u0446\u043a\u043e\u0435 \u0442\u0435\u043b\u0435\u0432\u0438\u0434\u0435\u043d\u0438\u0435","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.btv.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Person","@id":"https:\/\/www.btv.md\/#\/schema\/person\/b459536a60194184218c40dec648134d","name":"admin"}]}},"_links":{"self":[{"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/posts\/45126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/comments?post=45126"}],"version-history":[{"count":0,"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/posts\/45126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/media\/45127"}],"wp:attachment":[{"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/media?parent=45126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/categories?post=45126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.btv.md\/ro\/wp-json\/wp\/v2\/tags?post=45126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}